{"id":95754,"date":"2026-05-14T00:02:13","date_gmt":"2026-05-14T03:02:13","guid":{"rendered":"https:\/\/screamyell.com.br\/site\/?p=95754"},"modified":"2026-06-03T15:03:14","modified_gmt":"2026-06-03T18:03:14","slug":"o-diretor-fabio-meira-fala-sobre-mambembe-seu-terceiro-longa-eu-quis-que-o-filme-tambem-fosse-livre","status":"publish","type":"post","link":"https:\/\/screamyell.com.br\/site\/2026\/05\/14\/o-diretor-fabio-meira-fala-sobre-mambembe-seu-terceiro-longa-eu-quis-que-o-filme-tambem-fosse-livre\/","title":{"rendered":"Cinema: &#8220;Eu quis que o filme tamb\u00e9m fosse livre&#8221;, diz Fabio Meira sobre &#8220;Mambembe&#8221;, seu terceiro longa"},"content":{"rendered":"<h2 style=\"text-align: center;\"><strong>entrevista de\u00a0<a href=\"https:\/\/www.facebook.com\/joao.paulo.barreto.824529\" target=\"_blank\" rel=\"noopener noreferrer\">Jo\u00e3o Paulo Barreto<\/a><\/strong><\/h2>\n<p style=\"text-align: justify;\">O fasc\u00ednio pelo circo move &#8220;<a href=\"https:\/\/screamyell.com.br\/site\/2024\/11\/02\/tres-filmes-da-48a-mostra-sp-a-cozinha-mambembe-dahomey\/\" target=\"_blank\" rel=\"noopener\">Mambembe&#8221;<\/a> (2026). Por\u00e9m, n\u00e3o somente pelo circo em um aspecto rom\u00e2ntico ou idealizado, mas, tamb\u00e9m, encontrando formas de se conectar com as pessoas que fazem parte daquele universo distante de qualquer glamour e criando um elo de identifica\u00e7\u00e3o com seu p\u00fablico tanto nas cadeiras sob a tenda do picadeiro, quanto nas poltronas do cinema. O filme do diretor Fabio Meira prima por criar esse modo de conex\u00e3o com suas tr\u00eas figuras centrais, mulheres que vivem em um circo itinerante e se encontram na busca por um norte em suas pr\u00f3prias vidas.<\/p>\n<p style=\"text-align: justify;\">Com \u00cdndia Morena, uma das figuras referenciais em rela\u00e7\u00e3o \u00e0 cultura circense no Brasil, a maturidade de uma mulher segura de suas convic\u00e7\u00f5es e afirmativa no que quer em termos de felicidade para sua pr\u00f3pria vida \u00e9 apresentada com altivez. Vivendo a si mesma como personagem do filme que mescla aspectos documentais com fic\u00e7\u00e3o, \u00cdndia capta e transmite com precis\u00e3o a ideia de uma vida calejada na dedica\u00e7\u00e3o ao circo. Comanda a apresenta\u00e7\u00e3o dos espet\u00e1culos com a mesma seguran\u00e7a que comanda seus pr\u00f3prios anseios e impulsos afetivos, demonstrados em alguns momentos do filme.<\/p>\n<p style=\"text-align: justify;\">Junto a ela, Madona Show, tamb\u00e9m artista circense, tem na vida com os dois p\u00e9s na estrada uma busca por seu pr\u00f3prio sentido de continuar atr\u00e1s desse mesmo equil\u00edbrio e lugar de pertencimento. &#8220;Mambembe&#8217; traz Madona falando de sua trajet\u00f3ria, abordando uma ren\u00fancia pessoal perante a necessidade de cuidar de sua m\u00e3e doente. Fechando esse trio, a personagem tamb\u00e9m real J\u00e9ssica \u00e9 vivida pela atriz e assistente de dire\u00e7\u00e3o Dandara Ohana. Em sua abertura, a J\u00e9ssica real surge em cena, encantadora, e faz o pr\u00f3prio diretor comentar sobre seu magnetismo para com a c\u00e2mera. Na juventude da J\u00e9ssica encarnada por Dandara, um reflexo daquela dos sonhos que \u00cdndia e Madona nutriram por toda a sua vida.<\/p>\n<p style=\"text-align: justify;\">Ao refletir sobre a influ\u00eancia da cultura circense em sua pr\u00f3pria vida e sobre o aspecto itinerante daquela vida na estrada, o diretor e roteirista Fabio Meira insere Rui, um personagem de um misterioso top\u00f3grafo, vivido por Murilo Grossi, e que espelha seu pr\u00f3prio pai, tamb\u00e9m top\u00f3grafo que viajou o Brasil a trabalho e que surge no filme em imagens de arquivo. Na sua narra\u00e7\u00e3o, Meira desenvolve essa rela\u00e7\u00e3o e como a perda o afetou. Projeto iniciado h\u00e1 quinze anos, &#8220;Mambembe&#8221; chega aos cinemas ap\u00f3s dois outros longas de Fabio Meira, no caso &#8220;As Duas Irenes&#8221; (2017) e &#8220;Tia Virginia&#8221; (2023).<\/p>\n<p style=\"text-align: justify;\">No papo com o Scream &amp; Yell, Fabio Meira fala sobre o processo de cria\u00e7\u00e3o de &#8220;Mambembe&#8221;.<\/p>\n<p><iframe loading=\"lazy\" title=\"MAMBEMBE - dire\u00e7\u00e3o Fabio Meira - 14 de Maio nos cinemas\" width=\"747\" height=\"420\" src=\"https:\/\/www.youtube.com\/embed\/JUaty9Lr6uk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>Dentro de um processo de produ\u00e7\u00e3o que durou mais de dez anos e de montagem que chegou a cinco anos, o roteiro do filme passou por muitas mudan\u00e7as nesse per\u00edodo?<\/strong><br \/>\nO roteiro era bem diferente. O filme que pensei era completamente diferente do filme que acabou acontecendo. Acabei tendo que me colocar como personagem. Toda essa parte da constru\u00e7\u00e3o do filme, do processo dele sendo feito, n\u00e3o fazia parte da idealiza\u00e7\u00e3o inicial. Foram quinze anos do processo de constru\u00e7\u00e3o desse trabalho. Por exemplo, eu j\u00e1 tinha gravado aquela narra\u00e7\u00e3o da primeira cena em que eu comentava. No momento em que decidi que o processo tamb\u00e9m faria parte do filme, acabei me colocando mais como personagem. E a hist\u00f3ria do meu pai aconteceu durante o pr\u00f3prio processo de fazer o filme. Foram, no total, mais de cinco anos de montagem. E a\u00ed a hist\u00f3ria vai se transformando e a vida, tamb\u00e9m. Quando decidi que o processo ia fazer parte, tamb\u00e9m decidi que eu ia colocar um pouco da motiva\u00e7\u00e3o para fazer o filme. Decidi falar que existia um paralelo entre aquele personagem e meu pai. S\u00f3 que eu n\u00e3o sabia o que iria acontecer dois anos depois. Ent\u00e3o, quando eu achava que a montagem estava fechada, alguma coisa me levava a voltar a ela e terminar de encontrar o filme, que foi se transformando ao longo do tempo.<\/p>\n<p style=\"text-align: justify;\"><strong>No resultado final, vemos o processo de cria\u00e7\u00e3o do pr\u00f3prio filme sendo trazido, com os percal\u00e7os e atritos, comuns em qualquer produ\u00e7\u00e3o. E tem aquela cena na qual Murilo Grossi acaba se irritando durante uma cena. Como foi esse processo de inserir no longa essa constru\u00e7\u00e3o t\u00e9cnica?<\/strong><br \/>\nEssa \u00e9, geralmente, a primeira pergunta que aparece quando eu fa\u00e7o sess\u00f5es de apresenta\u00e7\u00e3o do filme. As pessoas se dividem na plateia entre os que acham que aquilo \u00e9 encenado, e os que acham que aquilo, realmente, aconteceu. E eu tenho combinado com o Murilo (Grossi, ator do filme) que a gente nunca responde. Essa \u00e9 uma resposta que eu nunca dou. Isso \u00e9 exatamente o que me interessa no filme. Que as pessoas n\u00e3o saibam o que \u00e9 fic\u00e7\u00e3o e o que \u00e9 realidade. Foi isso que procuramos na montagem o tempo inteiro. Fico muito feliz quando uma plateia entra em debate, cada um com uma certeza, explicando o motivo de como aquela pessoa tem certeza de que aquela cena n\u00e3o foi encenada. E os outros, n\u00e3o. Assim como voc\u00ea falou. Voc\u00ea, por exemplo, tem certeza que ela foi real. Mas tem gente que faz teorias, falando sobre quando, depois, ele derruba o lixo. Isso era o que a gente mais queria que acontecesse. Que n\u00e3o soubessem o que \u00e9 verdade e o que encena\u00e7\u00e3o no pr\u00f3prio filme.<\/p>\n<figure id=\"attachment_95757\" aria-describedby=\"caption-attachment-95757\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-95757\" src=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_Madona_India_Dandara_-credito-divulgacao-Roseira-Filmes.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_Madona_India_Dandara_-credito-divulgacao-Roseira-Filmes.jpg 750w, https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_Madona_India_Dandara_-credito-divulgacao-Roseira-Filmes-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-95757\" class=\"wp-caption-text\"><em>Madona, India e Dandara<\/em><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Em paralelo ao processo de cria\u00e7\u00e3o de &#8220;Mambembe&#8221;, voc\u00ea ainda d<\/strong><strong>irigiu outros &#8220;As Duas Irenes&#8221; (2017) e &#8220;Tia Virginia&#8221; (2023). Como foi voltar a &#8220;Mambembe&#8221; durante todos esse anos?<\/strong><br \/>\n\u00c9 muito interessante essa pergunta, Jo\u00e3o. Porque \u00e9 um filme feito por um diretor muito jovem, com muita energia, e\u00a0 montado por um diretor um pouco mais amadurecido, depois de ter feito outros dois filmes. Ent\u00e3o, acho que o filme tem isso de interessante. Porque ele coloca o mesmo profissional, o mesmo artista, em dois momentos distintos da vida. Porque tem uma transforma\u00e7\u00e3o profissional de 15 anos ali. O pr\u00f3prio fato de ter feito e lan\u00e7ado dois longas porque a gente aprende muito sobre o filme, tamb\u00e9m, quando o apresentamos para o p\u00fablico. Acho que amadureci nesse processo e consegui olhar para aquele material de 2010 com outro olhar. Mas tamb\u00e9m muito encantado com o diretor de 2010, e sua grande energia e sua grande vontade de fazer um primeiro filme.<\/p>\n<p style=\"text-align: justify;\"><strong>De onde veio seu fasc\u00ednio pelo circo, F\u00e1bio?<\/strong><br \/>\nNa estreia do filme no Rio de Janeiro, eu, \u00cdndia e Madona fomos na Escola Nacional de Circo, um lugar que eu nunca tinha ido. E a diretora da escola me fez a mesma pergunta. E \u00e9 um fasc\u00ednio que vem desde a inf\u00e2ncia. Sou de Goi\u00e2nia, uma cidade muito conservadora. Ent\u00e3o, quando aqueles circos iam para l\u00e1, ocupavam aqueles terrenos baldios e faziam aqueles espet\u00e1culos, para uma crian\u00e7a j\u00e1 diferente em um terreno completamente conservador, era como se fosse um vislumbre de liberdade, sabe? Ent\u00e3o, era como se eu pudesse vislumbrar outras vidas poss\u00edveis que n\u00e3o aquela vida mon\u00f3tona e vigiada que eu tinha em Goi\u00e2nia. Ent\u00e3o, acho que meu fasc\u00ednio vem dali. Vem da liberdade daqueles artistas e de uma outra maneira de vida que o circo me mostrava. Que era poss\u00edvel ter uma vida diferente al\u00e9m daquela vida comum a que eu achava que estava condenado, sabe? Eu fiz aquela viagem que est\u00e1 no filme. Foram oito estados, quatro semanas e 63 circos. E fui conhecendo muita gente que tinha fugido com o circo. E \u00e9 exatamente isso. O circo \u00e9 fascinante. Ele \u00e9 muito envolvente. Ent\u00e3o, de alguma maneira, aquilo fica embrenhado na gente. Quem tem o esp\u00edrito um pouco mais aventureiro, um pouco mais livre, acaba se encantando por esse universo.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-95758 aligncenter\" src=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_divulgacaoRoseiraFilmes.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_divulgacaoRoseiraFilmes.jpg 750w, https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_divulgacaoRoseiraFilmes-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>E \u00e9 curioso porque em cada personagem real do filme, como a Madona Show e a \u00cdndia Morena que aparecem j\u00e1 ap\u00f3s tantos anos do come\u00e7o das filmagens, n\u00e3o surge um sentimento de nostalgia, mas de completude tanto pelo trabalho como pela vida circense. Como foi esse reencontro para voc\u00ea?<\/strong><br \/>\nTem uma coisa, Jo\u00e3o, que era muito interessante. Porque teve esse processo que levou quinze anos. E tinha uma coisa que, claro, era muito dif\u00edcil para mim, que era conviver com um filme incompleto. Porque, de alguma maneira, aquilo n\u00e3o deixa de ser um fracasso. Fazer uma coisa durante mais de dez anos. \u00c9 uma coisa que te d\u00f3i no peito. E com as atrizes, eu sentia um pouco isso tamb\u00e9m. Porque, por exemplo, o caso espec\u00edfico da Madona foi interessante porque as pessoas, os amigos dela, achavam que ela tinha inventado, que ela nunca tinha feito um filme. Eles falavam: &#8220;Ah, mas voc\u00ea fez um filme, mas cad\u00ea esse filme? Ele n\u00e3o existe.&#8221; Ent\u00e3o, quando ligamos para ela, mais de 10 anos depois, para fazer a \u00faltima entrevista, ela achou que fosse um trote. E a mesma coisa quando ligamos ap\u00f3s eu ter sumido mais um pouco. Porque o processo foi sempre longo. E quando a chamamos para estreia no Festival do Rio, ela, de novo, achou que era uma brincadeira. Ma ela veio e foi muito bonito. Foi sua primeira viagem de avi\u00e3o. A \u00cdndia n\u00e3o, ela me esperava a qualquer momento. Porque a \u00cdndia \u00e9 aquela sede de vida, aquela confian\u00e7a de si mesma. Todo lugar que ela chega, ela \u00e9 uma estrela. Na visita \u00e0 Escola Nacional de Circo, ela puxou tudo. Fez uma encena\u00e7\u00e3o com as jovens estudantes de circo. Enquanto a Madonna achou que eu nunca mais fosse voltar, a \u00cdndia sempre me esperou. Nessa ocasi\u00e3o, inclusive, quando a Madona iria viajar para o Rio, antes, ela foi at\u00e9 a cidade da m\u00e3e, que ficava a uns 200 km de dist\u00e2ncia, falar para ela que estava indo ao Rio de Janeiro apresentar um filme. E isso a m\u00e3e, que j\u00e1 estava com mais de 90 anos, pediu \u00e0 filha que n\u00e3o deixasse de visitar o Cristo Redentor. E ela foi. Agora, ela voltou para a estreia do filme, s\u00f3 que a m\u00e3e dela acabou de falecer. Isso fez com eu que eu lembrasse da hist\u00f3ria do meu pr\u00f3prio pai. Como, por ser um filme de um processo longo, ele acaba ganhando novos significados a partir da pr\u00f3pria vida. Ent\u00e3o, a viagem da Madona foi marcada por um pedido da m\u00e3e: &#8220;N\u00e3o deixe de ir ao Cristo&#8221;. E essa segunda viagem ao Rio, ela j\u00e1 n\u00e3o tem a m\u00e3e. Mas, ao mesmo tempo, ela voltou at\u00e9 a casa da m\u00e3e, mesmo j\u00e1 falecida, porque, de alguma maneira, ela sabia que a m\u00e3e ainda estava l\u00e1. Acho\u00a0 isso muito bonito e tem muito a ver com o filme.<\/p>\n<p style=\"text-align: justify;\"><strong>O filme transmite para a gente essa sensa\u00e7\u00e3o daquelas pessoas pertencerem \u00e0quela vida circense e curioso fazer esse paralelo com a vida do artista como um todo.<\/strong><br \/>\nSer artista \u00e9 uma sina. Ent\u00e3o, se voc\u00ea for analisar, se for prestar aten\u00e7\u00e3o no que \u00e9 o filme, e no que \u00e9 o artista de circo e no que \u00e9 o artista de cinema, s\u00f3 pode ser sina. Porque o mundo est\u00e1 o tempo inteiro dizendo n\u00e3o. O tempo inteiro s\u00e3o barreiras e dificuldades. S\u00e3o chuvas e tempestades no circo. S\u00e3o problemas de or\u00e7amento no cinema, ou s\u00e3o problemas de produ\u00e7\u00e3o. Mas a gente n\u00e3o consegue fazer outra coisa. S\u00f3 nos realizamos como seres humanos se estivermos exercendo a nossa profiss\u00e3o, o nosso talento. Ent\u00e3o, eu acho que, realmente, ser artista \u00e9 uma sina. E n\u00e3o \u00e9 para qualquer um. \u00c9 para quem \u00e9 resiliente e para quem persiste. \u00c9 preciso resili\u00eancia, persist\u00eancia e muita coragem. Isso sobra em \u00cdndia Morena e, tamb\u00e9m, sobra em Madona e em Jessica.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-95759 aligncenter\" src=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_India_Morena_e_Maviavel_-credito-divulgacao-Roseira-Filmes2.jpg\" alt=\"\" width=\"750\" height=\"440\" srcset=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_India_Morena_e_Maviavel_-credito-divulgacao-Roseira-Filmes2.jpg 750w, https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_India_Morena_e_Maviavel_-credito-divulgacao-Roseira-Filmes2-300x176.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>H\u00e1 uma qu\u00edmica fica muito bonita entre as tr\u00eas, \u00cdndia, Madona e J\u00e9ssica, vivida por Dandara Ohana.<\/strong><br \/>\nSim. E Dandara foi apagar um inc\u00eandio, n\u00e9? Porque a J\u00e9ssica real n\u00e3o p\u00f4de viajar. Ent\u00e3o, acaba que quem faz o papel da terceira menina de circo \u00e9 uma atriz, mas n\u00e3o uma artista de circo, como era o meu projeto inicial.<\/p>\n<p style=\"text-align: justify;\"><strong>Sensa\u00e7\u00e3o de dever cumprido ap\u00f3s tantos anos?<\/strong><br \/>\nSim. Dever cumprido. Agora o filme chega ao cinema e cumpre o objetivo final dele. \u00c9 onde o filme, realmente, se estabelece. Quando ele vai ter sua estreia comercial na sala de cinema. E \u00e9 por isso que eu sinto que, agora, um ciclo se fecha. N\u00e3o s\u00f3 o ciclo do filme, mais um ciclo na minha vida. E tamb\u00e9m acho que, agora, estou abrindo espa\u00e7o para novos projetos. Porque esse, agora, eu estou entregando para o p\u00fablico. Dever cumprido.<\/p>\n<p style=\"text-align: justify;\"><strong>E a escolha de &#8220;Mambembe&#8221;, do Chico, na voz e imagem e Elza Soares em um filme t\u00e3o feminino tem um s\u00edmbolo bem grande.<\/strong><br \/>\n&#8220;Mambembe&#8221;, do Chico Buarque, fala sobre essa sina do artista. Sobre essa beleza, tamb\u00e9m. Por mais que seja ali de uma maneira improvisada, de uma maneira que n\u00e3o \u00e9 a ideal, mas o amor pela arte est\u00e1 ali. E eu acho que essa m\u00fasica traduz um pouco o filme. E com a Elza cantando foi uma coisa pela qual eu batalhei bastante tamb\u00e9m. Ent\u00e3o, fico feliz de ter conseguido isso para o filme. Ela e \u00cdndia se comunicam muito. S\u00e3o mulheres negras, fortes e apaixonantes. S\u00e3o mulheres muito cativantes. E com a letra do Chico, acho que fala um pouco sobre a liberdade do filme. Porque ningu\u00e9m espera que naquele momento vai vir um arquivo dos anos 1960 para fechar o filme. E isso \u00e9 justamente a beleza ali. E a\u00ed eu volto para a sua pergunta sobre o que me interessou no circo. Foi a liberdade. Eu quis que o filme tamb\u00e9m fosse livre.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-95756 aligncenter\" src=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_cartaz_alta-1.jpg\" alt=\"\" width=\"750\" height=\"1067\" srcset=\"https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_cartaz_alta-1.jpg 750w, https:\/\/screamyell.com.br\/site\/wp-content\/uploads\/2026\/05\/Mambembe_cartaz_alta-1-211x300.jpg 211w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>\u2013\u00a0<a href=\"https:\/\/www.facebook.com\/profile.php?id=100009655066720\" target=\"_blank\" rel=\"noopener noreferrer\">Jo\u00e3o Paulo Barreto\u00a0<\/a>\u00e9 jornalista, cr\u00edtico de cinema e curador do\u00a0<a href=\"http:\/\/coisadecinema.com.br\/xiii-panorama\/apresentacao\/panorama-2017\/\" target=\"_blank\" rel=\"noopener noreferrer\">Festival Panorama Internacional Coisa de Cinema<\/a>. Membro da Abraccine, colabora para o Jornal A Tarde, de Salvador, e \u00e9 autor de \u201c<a href=\"https:\/\/screamyell.com.br\/site\/2024\/11\/11\/entrevista-mitico-guitarrista-baiano-alvaro-assmar-ganha-biografia-joao-paulo-barreto-fala-sobre-uma-vida-blues\/\" target=\"_blank\" rel=\"noopener\">Uma Vida Blues<\/a>\u201d, biografia de \u00c1lvaro Assmar.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"&#8220;Mambembe&#8221; prima por criar um modo de conex\u00e3o com suas tr\u00eas figuras centrais, mulheres que vivem em um circo itinerante.\n<a class=\"moretag\" href=\"https:\/\/screamyell.com.br\/site\/2026\/05\/14\/o-diretor-fabio-meira-fala-sobre-mambembe-seu-terceiro-longa-eu-quis-que-o-filme-tambem-fosse-livre\/\"> [...]<\/a>","protected":false},"author":21,"featured_media":95760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[7447],"_links":{"self":[{"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/posts\/95754"}],"collection":[{"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/comments?post=95754"}],"version-history":[{"count":6,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/posts\/95754\/revisions"}],"predecessor-version":[{"id":96099,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/posts\/95754\/revisions\/96099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/media\/95760"}],"wp:attachment":[{"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/media?parent=95754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/categories?post=95754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/screamyell.com.br\/site\/wp-json\/wp\/v2\/tags?post=95754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}